{"id":4456,"date":"2026-02-16T13:50:03","date_gmt":"2026-02-16T13:50:03","guid":{"rendered":"https:\/\/lecoinbleu-immobilier.com\/?page_id=4456"},"modified":"2026-04-10T09:24:04","modified_gmt":"2026-04-10T09:24:04","slug":"lcb_baie_de_rades","status":"publish","type":"page","link":"https:\/\/www.lecoinbleu-immobilier.com\/en\/lcb_baie_de_rades\/","title":{"rendered":"LCB_Projet_Baie_de_Rades"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4456\" class=\"elementor elementor-4456\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f5ce51 elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"9f5ce51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5571b7d jltma-glass-effect-no\" data-id=\"5571b7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-649b386 elementor-widget__width-inherit jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"649b386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/35D6F0DE-CD8D-4813-AA54-1B0F0D11DC89-1024x683.webp\" class=\"attachment-large size-large wp-image-5554\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/35D6F0DE-CD8D-4813-AA54-1B0F0D11DC89-1024x683.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/35D6F0DE-CD8D-4813-AA54-1B0F0D11DC89-300x200.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/35D6F0DE-CD8D-4813-AA54-1B0F0D11DC89-768x512.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/35D6F0DE-CD8D-4813-AA54-1B0F0D11DC89-18x12.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/35D6F0DE-CD8D-4813-AA54-1B0F0D11DC89.webp 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f532797 elementor-absolute jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"f532797\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Your future exceptional location<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f157cc elementor-absolute jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2f157cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rades Bay<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd80f21 elementor-absolute jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"fd80f21\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Discover the Coin Bleu Projects<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9e7d04a e-con-full e-flex jltma-glass-effect-no e-con e-parent\" data-id=\"9e7d04a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0e9cf28 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"0e9cf28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-86c6258 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"86c6258\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c1c1d34 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"c1c1d34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4b790 elementor-widget-mobile__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ae4b790\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3672ba6 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"3672ba6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e8b970 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"0e8b970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Project<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0051c9a e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"0051c9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c906c05 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c906c05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3087fe1 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3087fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RADES BAY <br> Investing in a new living space between nature, sea and modernity<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6250e7c elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6250e7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Developed by Le Coin Bleu, La Baie de Rad\u00e8s is an exceptional residential development designed to create a modern, harmonious, and sustainable neighborhood south of Tunis. Conceived with a vision of responsible urban planning, this project offers a balanced living environment where housing, nature, and services coexist elegantly.\n\nDesigned as a true living space, the project includes plots for villas, small residential buildings, landscaped green spaces, promenades, and cycle paths, fostering a sense of community, sustainable mobility, and daily well-being. Dedicated spaces for local services and professional activities complement this vision, creating a vibrant and versatile neighborhood adapted to new lifestyles.\n\nLocated in a remarkable natural setting near a protected wetland and the coastline, La Baie de Rad\u00e8s offers a unique environment where nature remains central to the residential experience. Residents enjoy unobstructed views of a rich natural landscape, exceptional biodiversity, and a peaceful setting conducive to relaxation.\n<br>\n<br>\n\nBeyond a real estate project, La Baie de Rad\u00e8s reflects the vision of Le Coin Bleu: to develop sustainable living spaces while contributing to the preservation of local flora and fauna. This responsible approach stems from the conviction that protecting these ecosystems constitutes a precious legacy for future generations.\n<br>\n<br>\n\n\nToday, La Baie de Rad\u00e8s represents a rare investment opportunity, in a rapidly developing area, where quality of life, heritage value and respect for the environment combine to create a residential project for the future.\n<br>\n<br>\n\n\nRad\u00e8s Bay \u2014 investing in a sustainable living environment, between nature and modernity.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f8e349 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9f8e349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8edec3d e-con-full e-flex jltma-glass-effect-no e-con e-parent\" data-id=\"8edec3d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3f8e314 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"3f8e314\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e043d89 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"e043d89\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f44e0ad elementor-widget__width-auto elementor-absolute jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"f44e0ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Project Location<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df888c9 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"df888c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"650\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/02\/rades-1024x650.webp\" class=\"attachment-large size-large wp-image-4536\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/02\/rades-1024x650.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/02\/rades-300x191.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/02\/rades-768x488.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/02\/rades-18x12.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/02\/rades.webp 1288w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59b3472 elementor-widget__width-auto elementor-absolute jltma-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"59b3472\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maps.app.goo.gl\/P8CNeWjNfMNfFczP7\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"im im-location\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View on Google Maps<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92910d5 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"92910d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60f5c05 elementor-widget__width-auto elementor-absolute jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"60f5c05\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4111d71 elementor-widget-mobile__width-inherit elementor-widget__width-inherit jltma-glass-effect-no elementor-widget elementor-widget-shortcode\" data-id=\"4111d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    \n    <form id=\"custom-inscription-form-v2\" method=\"post\" aria-label=\"Formulaire de contact simplifi\u00e9\" novalidate action=\"\">\n        <input type=\"hidden\" name=\"action\" value=\"process_custom_form_v2\">\n        <input type=\"hidden\" name=\"nonce\" id=\"custom-form-v2-nonce\" value=\"fa3913eb5c\">\n        \n        <div class=\"custom-form-container\">\n            <div id=\"form-message-container-v2\" class=\"custom-form-notice\" style=\"display: none;\"><\/div>\n            \n            <!-- Champ Nom Complet consolid\u00e9 (au lieu de Nom + Pr\u00e9nom s\u00e9par\u00e9s) -->\n            <input type=\"text\" name=\"nom_complet\" placeholder=\"Full name * (minimum 3 characters)\" required value=\"\" class=\"form-field-v2 reset\">\n            <span class=\"field-error\" data-field=\"nom_complet\"><\/span>\n            \n            <input type=\"email\" name=\"email\" placeholder=\"E-mail address *\" required value=\"\" class=\"form-field-v2 reset\">\n            <span class=\"field-error\" data-field=\"email\"><\/span>\n            \n            <textarea name=\"message\" placeholder=\"Your message (optional - minimum 10 characters if filled in)\" class=\"form-field-v2 reset\"><\/textarea>\n            <span class=\"field-error\" data-field=\"message\"><\/span>\n            \n            <span class=\"custom-form-hint\">Fields marked with an * are required.<\/span>\n            \n            <div class=\"g-recaptcha-container\">\n                <div id=\"custom-form-v2-recaptcha\" class=\"g-recaptcha\" data-sitekey=\"6LcVCp4qAAAAAOKu9VE3uUGBSLtw0qYeHXhut92Y\"><\/div>\n            <\/div>\n            <div id=\"recaptcha-error-v2\" class=\"recaptcha-error\">V\u00e9rification Google reCAPTCHA \u00e9chou\u00e9, veuillez r\u00e9essayer.<\/div>\n        <\/div>\n    <input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00cb74c elementor-widget-mobile__width-inherit elementor-widget__width-inherit jltma-glass-effect-no elementor-widget elementor-widget-shortcode\" data-id=\"00cb74c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><button type=\"submit\" class=\"custom-form-button\" id=\"submit-form-v2\">\n                <span class=\"button-text\">Send<\/span>\n            <\/button><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f0c914 e-con-full e-flex jltma-glass-effect-no e-con e-parent\" data-id=\"0f0c914\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-dab66bf e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"dab66bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8a747d8 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"8a747d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f908eb1 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"f908eb1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e6a0e8 elementor-widget-mobile__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2e6a0e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57ccbcc e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"57ccbcc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cd95c1 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3cd95c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Some images from the project <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d81263e e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"d81263e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c9b30f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1c9b30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38e5102 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"38e5102\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-77f3344 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"77f3344\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-71cda97 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"71cda97\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65d3738 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"65d3738\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"571\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-5-e1772441886415-1024x571.webp\" class=\"attachment-large size-large wp-image-5000\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-5-e1772441886415-1024x571.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-5-e1772441886415-300x167.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-5-e1772441886415-768x428.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-5-e1772441886415-1536x857.webp 1536w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-5-e1772441886415-18x10.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-5-e1772441886415.webp 1542w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0ef993 elementor-widget__width-initial elementor-absolute elementor-view-default elementor-position-block-start elementor-mobile-position-block-start jltma-glass-effect-no elementor-widget elementor-widget-icon-box\" data-id=\"e0ef993\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"im im-photo-camera\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad43849 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"ad43849\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7633d8 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"f7633d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"569\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_2_lwsoptimized-1024x569.webp\" class=\"attachment-large size-large wp-image-1995\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_2_lwsoptimized-1024x569.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_2_lwsoptimized-300x167.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_2_lwsoptimized-768x427.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_2_lwsoptimized-18x10.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_2_lwsoptimized.webp 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e08713 elementor-widget__width-initial elementor-absolute elementor-view-default elementor-position-block-start elementor-mobile-position-block-start jltma-glass-effect-no elementor-widget elementor-widget-icon-box\" data-id=\"6e08713\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"im im-photo-camera\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfc082f e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"bfc082f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1d412c8 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"1d412c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5199fd9 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"5199fd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"602\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-4-1024x602.webp\" class=\"attachment-large size-large wp-image-4999\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-4-1024x602.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-4-300x176.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-4-768x451.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-4-1536x902.webp 1536w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-4-18x12.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-4.webp 1554w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62af705 elementor-widget__width-initial elementor-absolute elementor-view-default elementor-position-block-start elementor-mobile-position-block-start jltma-glass-effect-no elementor-widget elementor-widget-icon-box\" data-id=\"62af705\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"im im-photo-camera\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c119d12 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"c119d12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9596bc8 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"9596bc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"569\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_3_lwsoptimized-1024x569.webp\" class=\"attachment-large size-large wp-image-1996\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_3_lwsoptimized-1024x569.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_3_lwsoptimized-300x167.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_3_lwsoptimized-768x427.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_3_lwsoptimized-18x10.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_3_lwsoptimized.webp 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-139be97 elementor-widget__width-initial elementor-absolute elementor-view-default elementor-position-block-start elementor-mobile-position-block-start jltma-glass-effect-no elementor-widget elementor-widget-icon-box\" data-id=\"139be97\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"im im-photo-camera\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9374982 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"9374982\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b79a19e e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"b79a19e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8f3131 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"a8f3131\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3213547 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"3213547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"569\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_1_lwsoptimized-1024x569.webp\" class=\"attachment-large size-large wp-image-1994\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_1_lwsoptimized-1024x569.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_1_lwsoptimized-300x167.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_1_lwsoptimized-768x427.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_1_lwsoptimized-18x10.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2023\/04\/H_Rades_1_lwsoptimized.webp 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5312716 elementor-widget__width-initial elementor-absolute elementor-view-default elementor-position-block-start elementor-mobile-position-block-start jltma-glass-effect-no elementor-widget elementor-widget-icon-box\" data-id=\"5312716\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"im im-photo-camera\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e41645 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"6e41645\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d100660 popmake-4991 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"d100660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"588\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-3-1024x588.webp\" class=\"attachment-large size-large wp-image-4996\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-3-1024x588.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-3-300x172.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-3-768x441.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-3-1536x883.webp 1536w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-3-18x10.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/03\/Rades-3.webp 1603w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dfbe2e elementor-widget__width-initial elementor-absolute popmake-4991 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start jltma-glass-effect-no elementor-widget elementor-widget-icon-box\" data-id=\"0dfbe2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jltma-material-icon jltma-material-icon-play_circle_filled\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9e2b58 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d9e2b58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35da65b elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"35da65b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e09999 jltma-glass-effect-no\" data-id=\"5e09999\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2236fa0 elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"2236fa0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ed06f08 jltma-glass-effect-no\" data-id=\"ed06f08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f63c99d jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"f63c99d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"655\" height=\"358\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-DEV-01.webp\" class=\"attachment-large size-large wp-image-3242\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-DEV-01.webp 655w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-DEV-01-300x164.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-DEV-01-18x10.webp 18w\" sizes=\"(max-width: 655px) 100vw, 655px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0b92e40 jltma-glass-effect-no\" data-id=\"0b92e40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7d71e5 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"c7d71e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Immobili\u00e9re<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a55f46 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"0a55f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LE COIN BLEU<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e28382c elementor-widget__width-inherit jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"e28382c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"383\" src=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/footer-1024x383.webp\" class=\"attachment-large size-large wp-image-3104\" alt=\"\" srcset=\"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/footer-1024x383.webp 1024w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/footer-300x112.webp 300w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/footer-768x288.webp 768w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/footer-18x7.webp 18w, https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/footer.webp 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d27cb1a elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"d27cb1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f60cef1 jltma-glass-effect-no\" data-id=\"f60cef1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a86979 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6a86979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A Modern &amp; Responsible Approach<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47d908a jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"47d908a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b> \u00a9 2026 Le Coin Bleu. All rights reserved.<\/b> <br>\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ead70e2 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"ead70e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\n\nThe content, images, texts and architecture of this site are protected by intellectual property laws. Any reproduction, in whole or in part, is prohibited without prior authorization.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Votre futur lieu d&rsquo;exception La Baie de Rad\u00e9s D\u00e9couvrez les Projets du Coin Bleu Le Projet LA BAIE DE RAD\u00c8S Investir dans un nouveau lieu de vie entre nature, mer et modernit\u00e9 D\u00e9velopp\u00e9 par Le Coin Bleu, La Baie de Rad\u00e8s est un projet de lotissement d\u2019exception imagin\u00e9 pour cr\u00e9er un quartier r\u00e9sidentiel moderne, harmonieux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3243,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4456","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LCB_Projet_Baie_de_Rades - Le Coin Bleu | Entreprise Socialement Responsable<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LCB_Projet_Baie_de_Rades - Le Coin Bleu | Entreprise Socialement Responsable\" \/>\n<meta property=\"og:description\" content=\"Votre futur lieu d&rsquo;exception La Baie de Rad\u00e9s D\u00e9couvrez les Projets du Coin Bleu Le Projet LA BAIE DE RAD\u00c8S Investir dans un nouveau lieu de vie entre nature, mer et modernit\u00e9 D\u00e9velopp\u00e9 par Le Coin Bleu, La Baie de Rad\u00e8s est un projet de lotissement d\u2019exception imagin\u00e9 pour cr\u00e9er un quartier r\u00e9sidentiel moderne, harmonieux [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Coin Bleu | Entreprise Socialement Responsable\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T09:24:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-01.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t<meta property=\"og:image:height\" content=\"324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/\",\"url\":\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/\",\"name\":\"LCB_Projet_Baie_de_Rades - Le Coin Bleu | Entreprise Socialement Responsable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/LCB-LOGOS-01.webp\",\"datePublished\":\"2026-02-16T13:50:03+00:00\",\"dateModified\":\"2026-04-10T09:24:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/LCB-LOGOS-01.webp\",\"contentUrl\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/LCB-LOGOS-01.webp\",\"width\":655,\"height\":324},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lecoinbleu-immobilier.com\\\/lcb_baie_de_rades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LCB_Projet_Baie_de_Rades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/en\\\/\",\"name\":\"Le Coin Bleu | Entreprise Socialement Responsable\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lecoinbleu-immobilier.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LCB_Projet_Baie_de_Rades - Le Coin Bleu | Entreprise Socialement Responsable","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/","og_locale":"en_GB","og_type":"article","og_title":"LCB_Projet_Baie_de_Rades - Le Coin Bleu | Entreprise Socialement Responsable","og_description":"Votre futur lieu d&rsquo;exception La Baie de Rad\u00e9s D\u00e9couvrez les Projets du Coin Bleu Le Projet LA BAIE DE RAD\u00c8S Investir dans un nouveau lieu de vie entre nature, mer et modernit\u00e9 D\u00e9velopp\u00e9 par Le Coin Bleu, La Baie de Rad\u00e8s est un projet de lotissement d\u2019exception imagin\u00e9 pour cr\u00e9er un quartier r\u00e9sidentiel moderne, harmonieux [&hellip;]","og_url":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/","og_site_name":"Le Coin Bleu | Entreprise Socialement Responsable","article_modified_time":"2026-04-10T09:24:04+00:00","og_image":[{"width":655,"height":324,"url":"https:\/\/lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-01.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/","url":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/","name":"LCB_Projet_Baie_de_Rades - Le Coin Bleu | Entreprise Socialement Responsable","isPartOf":{"@id":"https:\/\/www.lecoinbleu-immobilier.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/#primaryimage"},"image":{"@id":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-01.webp","datePublished":"2026-02-16T13:50:03+00:00","dateModified":"2026-04-10T09:24:04+00:00","breadcrumb":{"@id":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/#primaryimage","url":"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-01.webp","contentUrl":"https:\/\/www.lecoinbleu-immobilier.com\/wp-content\/uploads\/2026\/01\/LCB-LOGOS-01.webp","width":655,"height":324},{"@type":"BreadcrumbList","@id":"https:\/\/lecoinbleu-immobilier.com\/lcb_baie_de_rades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lecoinbleu-immobilier.com\/en\/"},{"@type":"ListItem","position":2,"name":"LCB_Projet_Baie_de_Rades"}]},{"@type":"WebSite","@id":"https:\/\/www.lecoinbleu-immobilier.com\/en\/#website","url":"https:\/\/www.lecoinbleu-immobilier.com\/en\/","name":"Le Coin Bleu | Entreprise Socialement Responsable","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lecoinbleu-immobilier.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/pages\/4456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/comments?post=4456"}],"version-history":[{"count":90,"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/pages\/4456\/revisions"}],"predecessor-version":[{"id":6116,"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/pages\/4456\/revisions\/6116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/media\/3243"}],"wp:attachment":[{"href":"https:\/\/www.lecoinbleu-immobilier.com\/en\/wp-json\/wp\/v2\/media?parent=4456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}